{"id":35,"date":"2016-08-10T17:21:14","date_gmt":"2016-08-10T21:21:14","guid":{"rendered":"https:\/\/www.tucsonmuseumofart.org\/?page_id=35"},"modified":"2021-08-04T22:04:31","modified_gmt":"2021-08-05T05:04:31","slug":"contemporary-art","status":"publish","type":"page","link":"https:\/\/www.tucsonmuseumofart.org\/es\/contemporary-art\/","title":{"rendered":"Arte contempor\u00e1neo"},"content":{"rendered":"<div id='av_section_1'  class='avia-section av-bu027-bae04e38b6dd84ab5da4195cf28e4577 main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-bg-style-parallax av-minimum-height av-minimum-height-50 av-height-50  container_wrap fullsize'   data-av_minimum_height_pc='50' data-av_min_height_opt='50'><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-35'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-b2fe3-adf85b017d83cb20295767c921e79de0\">\n#top .av-special-heading.av-b2fe3-adf85b017d83cb20295767c921e79de0{\npadding-bottom:0;\nfont-size:40px;\n}\nbody .av-special-heading.av-b2fe3-adf85b017d83cb20295767c921e79de0 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-b2fe3-adf85b017d83cb20295767c921e79de0 .av-special-heading-tag{\nfont-size:40px;\n}\n.av-special-heading.av-b2fe3-adf85b017d83cb20295767c921e79de0 .av-subheading{\nfont-size:20px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-b2fe3-adf85b017d83cb20295767c921e79de0 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-b2fe3-adf85b017d83cb20295767c921e79de0 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-b2fe3-adf85b017d83cb20295767c921e79de0 av-special-heading-h1 custom-color-heading blockquote modern-quote modern-centered  avia-builder-el-1  avia-builder-el-no-sibling  av-inherit-size'><h1 class='av-special-heading-tag'  itemprop=\"headline\"  >Arte Contempor\u00e1neo | arte contemporaneo<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='av_section_2'  class='avia-section av-aletb-8021c0d315976fbb2fad0089154f8c99 main_color avia-section-default avia-no-shadow  avia-builder-el-2  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-35'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-a2y8b-9321023f016e6c650fc30549cc9d44a7\">\n.flex_column.av-a2y8b-9321023f016e6c650fc30549cc9d44a7{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-a2y8b-9321023f016e6c650fc30549cc9d44a7 av_one_half  avia-builder-el-3  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding'     ><p><section  class='av_textblock_section av-9e3ef-83bb78b069b87a530b35efd79d029c23'   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>La colecci\u00f3n de Arte Contempor\u00e1neo est\u00e1 compuesta por m\u00e1s de 1.800 obras de arte desde 1970 hasta la actualidad. Es una de las \u00e1reas de colecci\u00f3n m\u00e1s diversas del museo en cuanto a artistas, perspectivas y medios, incluidas pinturas, fotograf\u00edas, grabados, esculturas, instalaciones, videos y artesan\u00edas. La colecci\u00f3n incluye obras de artistas BIPOC y un n\u00famero creciente de artistas que identifican a mujeres de todo Estados Unidos y el mundo. La amplia gama de artistas y obras de arte dentro de estas propiedades presenta perspectivas globales y tambi\u00e9n destaca el arte contempor\u00e1neo que es relevante para el suroeste de Estados Unidos.<\/p>\n<p>La colecci\u00f3n se form\u00f3 por primera vez a principios de la d\u00e9cada de 1970 mediante compras continuas del Festival de Tucson y las exposiciones de la Bienal de Arizona. Ha crecido en los \u00faltimos treinta a\u00f1os en estatura y alcance a trav\u00e9s de adquisiciones, esfuerzos de recaudaci\u00f3n de fondos de la Sociedad de Arte Contempor\u00e1neo y donantes y benefactores individuales. Los artistas reconocidos internacionalmente en la colecci\u00f3n incluyen a Robert Colescott, John Chamberlain, Viola Frey, Enrique Martinez Celaya, Wendy Red Star, Joyce Scott y Kara Walker. Las obras de artistas del suroeste de Estados Unidos incluyen a Kate Breakey, Alice Briggs, Karlito Miller Espinosa, Fausto Fernandez, Matthew Magee, Anh-Thuy Nguyen, Alfred Quiroz, Jaune Quick-to-See Smith y Papay Solomon.<\/p>\n<hr \/>\n<p>La colecci\u00f3n de Arte Contempor\u00e1nea est\u00e1 compuesta por m\u00e1s de 1.800 obras de arte que datan desde 1970 hasta la actualidad. Es una de las \u00e1reas de colecci\u00f3n m\u00e1s diversas del museo, con respecto a artistas, perspectivas y medios. Esta incluye pinturas, fotograf\u00edas, grabados, esculturas, instalaciones, videos y artesan\u00edas. Tambi\u00e9n incluye obras de artistas (BIPOC) y de un n\u00famero creciente de artistas. que se identifican como mujeres de todos los Estados Unidos y el mundo. La amplia gama de artistas y obras de arte presenta perspectivas globales y tambi\u00e9n destaca el arte contempor\u00e1neo que es relevante para el suroeste de Estados Unidos.<\/p>\n<p>La colecci\u00f3n se form\u00f3 por primera vez, a principios de la d\u00e9cada de 1970, gracias a las compras continuas durante el Festival de Tucson y las exposiciones de la Bienal de Arizona. Ha crecido en los \u00faltimos treinta a\u00f1os en tama\u00f1o as\u00ed como su alcance, a trav\u00e9s de la adquisici\u00f3n de donaciones, esfuerzos de recaudaci\u00f3n de fondos de la Sociedad de Arte Contempor\u00e1neo y de los donantes y benefactores individuales. Los artistas que han sido reconocidos internacionalmente y est\u00e1n incluidos en la colecci\u00f3n son: Robert Colescott, , John Chamberlain, Viola Frey, Enrique Martinez Celaya Wendy Red Star, Joyce Scott y Kara Walker. Las obras de artistas del suroeste de Estados Unidos incluyen a Kate Breakey, Alice Briggs, Karlito Miller Espinosa, Fausto Fernandez, Matthew Magee, Anh-Thuy Nguyen, Alfred Quiroz, Jaune Quick-to-See Smith y Papay Solomon.<\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-31ab-f18624b4d0c40a1bec127f3f24a3781a\">\n#top .hr.hr-invisible.av-31ab-f18624b4d0c40a1bec127f3f24a3781a{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-31ab-f18624b4d0c40a1bec127f3f24a3781a hr-invisible  avia-builder-el-5  el_after_av_textblock  el_before_av_button'><span class='hr-inner'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<div  class='avia-button-wrap av-7u0q7-a967354ccce9836dd59e9ce5ba8532a9-wrap avia-button-left  avia-builder-el-6  el_after_av_hr  avia-builder-el-last'><a href='http:\/\/tucsonmuseumofart.pastperfectonline.com\/search'  class='avia-button av-7u0q7-a967354ccce9836dd59e9ce5ba8532a9 av-link-btn avia-icon_select-no avia-size-large avia-position-left avia-color-dark'  target=\"_blank\"  rel=\"noopener noreferrer\"  aria-label=\"Colecci\u00f3n de b\u00fasqueda\"><span class='avia_iconbox_title' >Colecci\u00f3n de b\u00fasqueda<\/span><\/a><\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7cqnr-152343bf5c1d458f03014c5fa768e5a7\">\n.flex_column.av-7cqnr-152343bf5c1d458f03014c5fa768e5a7{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-7cqnr-152343bf5c1d458f03014c5fa768e5a7 av_one_half  avia-builder-el-7  el_after_av_one_half  avia-builder-el-last  flex_column_div av-zero-column-padding'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6mwvj-95fed881adc2eb9d57ffa6275da14912\">\n.avia-image-container.av-6mwvj-95fed881adc2eb9d57ffa6275da14912 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-6mwvj-95fed881adc2eb9d57ffa6275da14912 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-6mwvj-95fed881adc2eb9d57ffa6275da14912 av-styling-no-styling avia-align-center  avia-builder-el-8  el_before_av_textblock  avia-builder-el-first'   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-97 avia-img-lazy-loading-not-97 avia_image' src=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2016\/09\/Collazo_1991.236-1030x912.jpg\" alt='' title='collazo_1991-236'  height=\"912\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2016\/09\/Collazo_1991.236-1030x912.jpg 1030w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2016\/09\/Collazo_1991.236-450x399.jpg 450w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2016\/09\/Collazo_1991.236-300x266.jpg 300w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2016\/09\/Collazo_1991.236-768x680.jpg 768w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2016\/09\/Collazo_1991.236-1500x1329.jpg 1500w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2016\/09\/Collazo_1991.236-705x624.jpg 705w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k6lbq7v5-61372b9564405d6afcb21e8641aca2e9\">\n#top .av_textblock_section.av-k6lbq7v5-61372b9564405d6afcb21e8641aca2e9 .avia_textblock{\nfont-size:10px;\n}\n<\/style>\n<section  class='av_textblock_section av-k6lbq7v5-61372b9564405d6afcb21e8641aca2e9'   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Rafael Collazo, <em>Por el bien de todos nosotros<\/em>, 1987, \u00f3leo sobre tabla, 3 paneles. De la colecci\u00f3n del Museo de Arte de Tucson. Regalo de Riva Yares. 1991.236.<\/p>\n<\/div><\/section><\/p><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-60zln-c6ef665e65432330db0ca11c925a10cf\">\n.avia-section.av-60zln-c6ef665e65432330db0ca11c925a10cf{\nbackground-color:#000000;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_3'  class='avia-section av-60zln-c6ef665e65432330db0ca11c925a10cf main_color avia-section-default avia-no-border-styling  avia-builder-el-10  el_after_av_section  el_before_av_section  avia-bg-style-parallax av-minimum-height av-minimum-height-50 av-height-50  container_wrap fullsize'   data-av_minimum_height_pc='50' data-av_min_height_opt='50'><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-35'><div class='entry-content-wrapper clearfix'>\n<div id='av-masonry-1' class='av-masonry av-jw2r-900983d16719d90d964536939aa4d6c7 noHover av-fixed-size av-large-gap av-hover-overlay- av-masonry-animation-active av-masonry-col-6 av-caption-always av-caption-style- av-masonry-gallery' data-post_id=\"35\"><div class=\"av-masonry-container isotope av-js-disabled\"><div class='av-masonry-entry isotope-item av-masonry-item-no-image'><\/div><a href=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2017291-1030x858.jpg\" data-srcset=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2017291-1030x858.jpg 1030w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2017291-450x375.jpg 450w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2017291-300x250.jpg 300w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2017291-768x640.jpg 768w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2017291-1536x1280.jpg 1536w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2017291-2048x1707.jpg 2048w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2017291-1500x1250.jpg 1500w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2017291-705x588.jpg 705w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"imagen Wendy Red Star, Four Seasons: Oto\u00f1o, 2006, impresa en 2017, impresi\u00f3n con pigmentos de archivo en un trapo Sunset Fiber, 13\/15. Fondo Virginia Johnson. 2017.29.1\"  id='av-masonry-1-item-22851' data-av-masonry-item='22851' class='av-masonry-entry isotope-item post-22851 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Wendy Red Star, Four Seasons: Fall, 2006, impresa en 2017, impresi\u00f3n de pigmento de archivo en trapo Sunset Fiber, 13\/15. Fondo Virginia Johnson. 2017.29.1\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2017291-705x588.jpg);\"  title=\"Wendy Red Star, Four Seasons: Fall, 2006, impresa en 2017, impresi\u00f3n de pigmento de archivo en trapo Sunset Fiber, 13\/15. Fondo Virginia Johnson. 2017.29.1\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2018181-1030x772.jpg\" data-srcset=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2018181-1030x772.jpg 1030w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2018181-450x337.jpg 450w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2018181-300x225.jpg 300w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2018181-768x575.jpg 768w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2018181-1536x1151.jpg 1536w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2018181-2048x1535.jpg 2048w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2018181-1500x1124.jpg 1500w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2018181-705x528.jpg 705w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"imagen Yinka Shonibare, Cowboy Angel I, 2018, xilograf\u00eda con collage de tela, 19\/20. Compra de museo, Fondo Virginia Johnson. 2018.18.1\"  id='av-masonry-1-item-22852' data-av-masonry-item='22852' class='av-masonry-entry isotope-item post-22852 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Yinka Shonibare, Cowboy Angel I, 2018, xilograf\u00eda con collage de tela, 19\/20. Compra del Museo, Fondo Virginia Johnson. 2018.18.1\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2018181-705x528.jpg);\"  title=\"Yinka Shonibare, Cowboy Angel I, 2018, xilograf\u00eda con collage de tela, 19\/20. Compra del Museo, Fondo Virginia Johnson. 2018.18.1\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201929-796x1030.jpg\" data-srcset=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201929-796x1030.jpg 796w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201929-450x582.jpg 450w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201929-232x300.jpg 232w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201929-768x994.jpg 768w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201929-1187x1536.jpg 1187w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201929-1583x2048.jpg 1583w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201929-1159x1500.jpg 1159w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201929-545x705.jpg 545w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201929-scaled.jpg 1979w\" data-sizes=\"(max-width: 796px) 100vw, 796px\"  aria-label=\"imagen Enrique Martinez Celaya, La Lucha por el Aire, 2012, bronce, 2\/5. Donaci\u00f3n de la Sociedad de Arte Contempor\u00e1neo. 2019.29\"  id='av-masonry-1-item-22855' data-av-masonry-item='22855' class='av-masonry-entry isotope-item post-22855 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Enrique Martinez Celaya, La lucha por el aire, 2012, bronce, 2\/5. Donaci\u00f3n de la Sociedad de Arte Contempor\u00e1neo. 2019.29\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201929-545x705.jpg);\"  title=\"Enrique Martinez Celaya, La lucha por el aire, 2012, bronce, 2\/5. Donaci\u00f3n de la Sociedad de Arte Contempor\u00e1neo. 2019.29\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201061-749x1030.jpg\" data-srcset=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201061-749x1030.jpg 749w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201061-450x619.jpg 450w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201061-218x300.jpg 218w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201061-768x1056.jpg 768w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201061-1117x1536.jpg 1117w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201061-1489x2048.jpg 1489w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201061-1091x1500.jpg 1091w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201061-513x705.jpg 513w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201061-scaled.jpg 1862w\" data-sizes=\"(max-width: 749px) 100vw, 749px\"  aria-label=\"imagen Bailey Doogan, Five-Fingered Smile, 2010, carboncillo sobre papel imprimado. Comprado con fondos proporcionados por Robert J. Greenberg. 2010.6.1\"  id='av-masonry-1-item-22853' data-av-masonry-item='22853' class='av-masonry-entry isotope-item post-22853 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Bailey Doogan, Five-Fingered Smile, 2010, carboncillo sobre papel imprimado. Comprado con fondos proporcionados por Robert J. Greenberg. 2010.6.1\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201061-513x705.jpg);\"  title=\"Bailey Doogan, Five-Fingered Smile, 2010, carboncillo sobre papel imprimado. Comprado con fondos proporcionados por Robert J. Greenberg. 2010.6.1\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201632-1030x368.jpg\" data-srcset=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201632-1030x368.jpg 1030w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201632-450x161.jpg 450w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201632-300x107.jpg 300w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201632-768x274.jpg 768w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201632-1536x548.jpg 1536w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201632-2048x731.jpg 2048w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201632-1500x536.jpg 1500w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201632-705x252.jpg 705w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"imagen Matthius Zimmerman, The Volume Space 4, 2015, Impresi\u00f3n l\u00e1ser en nuevos medios sobre aluminio Dibond con acr\u00edlico. Regalo del Artista. 2016.3.2\"  id='av-masonry-1-item-22854' data-av-masonry-item='22854' class='av-masonry-entry isotope-item post-22854 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Matthius Zimmerman, The Volume Space 4, 2015, Impresi\u00f3n l\u00e1ser New media sobre aluminio Dibond con acr\u00edlico. Regalo del Artista. 2016.3.2\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/201632-705x252.jpg);\"  title=\"Matthius Zimmerman, The Volume Space 4, 2015, Impresi\u00f3n l\u00e1ser New media sobre aluminio Dibond con acr\u00edlico. Regalo del Artista. 2016.3.2\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2006222-1030x1030.jpg\" data-srcset=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2006222-1030x1030.jpg 1030w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2006222-450x450.jpg 450w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2006222-100x100.jpg 100w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2006222-300x300.jpg 300w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2006222-80x80.jpg 80w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2006222-768x768.jpg 768w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2006222-1536x1536.jpg 1536w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2006222-2048x2048.jpg 2048w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2006222-36x36.jpg 36w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2006222-180x180.jpg 180w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2006222-1500x1500.jpg 1500w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2006222-705x705.jpg 705w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"imagen Cheonae Kim, Sin t\u00edtulo, 2006, Flashe en panel. Regalo del Artista. 2006.22.2\"  id='av-masonry-1-item-22856' data-av-masonry-item='22856' class='av-masonry-entry isotope-item post-22856 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Cheonae Kim, Sin t\u00edtulo, 2006, Flashe en panel. Regalo del Artista. 2006.22.2\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2021\/08\/2006222-705x705.jpg);\"  title=\"Cheonae Kim, Sin t\u00edtulo, 2006, Flashe en panel. Regalo del Artista. 2006.22.2\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><\/div><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_4'  class='avia-section av-5av63-88101c3e06f5d619844722f0665c3d21 main_color avia-section-default avia-no-border-styling  avia-builder-el-12  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-35'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4fpkb-7874f1933499458f2de44146d03adb50\">\n#top .av-special-heading.av-4fpkb-7874f1933499458f2de44146d03adb50{\npadding-bottom:50px;\n}\nbody .av-special-heading.av-4fpkb-7874f1933499458f2de44146d03adb50 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-4fpkb-7874f1933499458f2de44146d03adb50 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-4fpkb-7874f1933499458f2de44146d03adb50 av-special-heading-h2 blockquote modern-quote modern-centered  avia-builder-el-13  el_before_av_masonry_entries  avia-builder-el-no-sibling'><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Exposiciones Actuales<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<div id='av-masonry-2' class='av-masonry av-40vov-dd3355c9743864642686327e9c53b515 noHover av-flex-size av-large-gap av-hover-overlay- av-masonry-animation-active av-masonry-col-4 av-caption-always av-caption-style- av-masonry-entries' data-post_id=\"35\"><div class=\"av-masonry-container isotope av-js-disabled\"><div class='av-masonry-entry isotope-item av-masonry-item-no-image'><\/div><a href=\"https:\/\/www.tucsonmuseumofart.org\/es\/exhibition\/artes-graficas-de-oaxaca\/\"  id='av-masonry-2-item-45074' data-av-masonry-item='45074' class='av-masonry-entry isotope-item post-45074 exhibition type-exhibition status-publish format-standard has-post-thumbnail hentry exhibition-status-current-exhibitions exhibition-status-feature-exhibitions  av-masonry-item-with-image' title=\"Artes Graphicas &#8211; Morales\"   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container'  ><img decoding=\"async\" width=\"705\" height=\"467\" fetchpriority=\"high\" class=\"wp-image-45075 avia-img-lazy-loading-not-45075\"  src=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/07\/Artes-Graphicas-Morales-705x467.jpg\" title=\"Artes Graphicas &#8211; Morales\" alt=\"\" srcset=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/07\/Artes-Graphicas-Morales-705x467.jpg 705w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/07\/Artes-Graphicas-Morales-300x199.jpg 300w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/07\/Artes-Graphicas-Morales-1030x682.jpg 1030w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/07\/Artes-Graphicas-Morales-768x508.jpg 768w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/07\/Artes-Graphicas-Morales-1536x1016.jpg 1536w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/07\/Artes-Graphicas-Morales-2048x1355.jpg 2048w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/07\/Artes-Graphicas-Morales-18x12.jpg 18w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/07\/Artes-Graphicas-Morales-1500x993.jpg 1500w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/07\/Artes-Graphicas-Morales-450x298.jpg 450w\" sizes=\"(max-width: 705px) 100vw, 705px\" \/><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title'  itemprop=\"headline\" >Artes Gr\u00e1ficas de Oaxaca<\/h3><div class='av-masonry-entry-content entry-content'  itemprop=\"text\" >August 08, 2026 \u2013 January 10, 2027<br \/>\r\nOn view Jon and Linda Ender Gallery<\/div><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/www.tucsonmuseumofart.org\/es\/exhibition\/fierce-bodies\/\"  id='av-masonry-2-item-44948' data-av-masonry-item='44948' class='av-masonry-entry isotope-item post-44948 exhibition type-exhibition status-publish format-standard has-post-thumbnail hentry exhibition-status-collection-exhibitions exhibition-status-current-exhibitions  av-masonry-item-with-image' title=\"2006191\"   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container'  ><img decoding=\"async\" width=\"495\" height=\"705\" fetchpriority=\"high\" class=\"wp-image-44949 avia-img-lazy-loading-not-44949\"  src=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/06\/2006191-495x705.jpg\" title=\"2006191\" alt=\"\" srcset=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/06\/2006191-495x705.jpg 495w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/06\/2006191-211x300.jpg 211w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/06\/2006191-724x1030.jpg 724w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/06\/2006191-768x1093.jpg 768w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/06\/2006191-1080x1536.jpg 1080w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/06\/2006191-1439x2048.jpg 1439w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/06\/2006191-8x12.jpg 8w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/06\/2006191-1054x1500.jpg 1054w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/06\/2006191-450x640.jpg 450w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/06\/2006191-scaled.jpg 1799w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title'  itemprop=\"headline\" >Fierce Bodies<\/h3><div class='av-masonry-entry-content entry-content'  itemprop=\"text\" >August 19, 2026 \u2013 July 3, 2027<br \/>\r\nOn view in Kasser Family Wing of Latin American Art \u2013 Rotating Bay\u00a0\u00a0<\/div><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/www.tucsonmuseumofart.org\/es\/exhibition\/another-frame\/\"  id='av-masonry-2-item-44597' data-av-masonry-item='44597' class='av-masonry-entry isotope-item post-44597 exhibition type-exhibition status-publish format-standard has-post-thumbnail hentry exhibition-status-collection-exhibitions exhibition-status-current-exhibitions  av-masonry-item-with-image' title=\"Carmen Mar\u2019n de Barreda\"   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container'  ><img decoding=\"async\" width=\"618\" height=\"705\" fetchpriority=\"high\" class=\"wp-image-44598 avia-img-lazy-loading-not-44598\"  src=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/95029011-618x705.jpg\" title=\"Carmen Mar\u2019n de Barreda\" alt=\"\" srcset=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/95029011-618x705.jpg 618w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/95029011-263x300.jpg 263w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/95029011-902x1030.jpg 902w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/95029011-768x877.jpg 768w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/95029011-1346x1536.jpg 1346w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/95029011-11x12.jpg 11w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/95029011-1314x1500.jpg 1314w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/95029011-450x514.jpg 450w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/95029011.jpg 1794w\" sizes=\"(max-width: 618px) 100vw, 618px\" \/><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title'  itemprop=\"headline\" >Another Frame: Lola \u00c1lvarez Bravo, Mariana Yampolsky, Graciela Iturbide, Flor Gardu\u00f1o<\/h3><div class='av-masonry-entry-content entry-content'  itemprop=\"text\" >April 02, 2026 \u2013 September 20, 2026<br \/>\r\nOn view in Kenneth and Judith Riskind\/Peter Salomon and Patricia Carr Morgan Gallery<\/div><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/www.tucsonmuseumofart.org\/es\/exhibition\/vivamos-siempre-como-hermanos\/\"  id='av-masonry-2-item-44588' data-av-masonry-item='44588' class='av-masonry-entry isotope-item post-44588 exhibition type-exhibition status-publish format-standard has-post-thumbnail hentry exhibition-status-collection-exhibitions exhibition-status-current-exhibitions  av-masonry-item-with-image' title=\"Vivamos\"   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container'  ><img decoding=\"async\" width=\"705\" height=\"570\" fetchpriority=\"high\" class=\"wp-image-44589 avia-img-lazy-loading-not-44589\"  src=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/Vivamos-705x570.jpg\" title=\"Vivamos\" alt=\"\" srcset=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/Vivamos-705x570.jpg 705w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/Vivamos-300x242.jpg 300w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/Vivamos-768x621.jpg 768w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/Vivamos-15x12.jpg 15w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/Vivamos-495x400.jpg 495w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/Vivamos-450x364.jpg 450w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2026\/03\/Vivamos.jpg 845w\" sizes=\"(max-width: 705px) 100vw, 705px\" \/><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title'  itemprop=\"headline\" >Vivamos Siempre Como Hermanos<\/h3><div class='av-masonry-entry-content entry-content'  itemprop=\"text\" >En curso<br \/>\r\nOn view in La Casa\u00a0Cordova\u00a0\u00a0<\/div><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><\/div><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3hi2z-b1a843fd93fb47494e0996a290c68f0d\">\n.avia-section.av-3hi2z-b1a843fd93fb47494e0996a290c68f0d .av-parallax .av-parallax-inner{\nbackground-repeat:no-repeat;\nbackground-image:url(https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2016\/08\/Current-Header-Image-scaled.jpg);\nbackground-position:50% 50%;\nbackground-attachment:scroll;\n}\n.avia-section.av-3hi2z-b1a843fd93fb47494e0996a290c68f0d .av-section-color-overlay{\nopacity:0.8;\nbackground-color:#000000;\n}\n<\/style>\n<div id='av_section_5'  class='avia-section av-3hi2z-b1a843fd93fb47494e0996a290c68f0d main_color avia-section-default avia-no-border-styling  avia-builder-el-15  el_after_av_section  avia-builder-el-last  av-parallax-section avia-bg-style-parallax av-section-color-overlay-active av-minimum-height av-minimum-height-100 av-height-100  container_wrap fullsize'  data-section-bg-repeat='no-repeat' data-av_minimum_height_pc='100' data-av_min_height_opt='100'><div class='av-parallax' data-avia-parallax-ratio='0.3' ><div class='av-parallax-inner main_color avia-full-stretch'><\/div><\/div><div class=\"av-section-color-overlay-wrap\"><div class=\"av-section-color-overlay\"><\/div><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-35'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-9oy3-930ed093a6c9b901085fa9835aecad3c\">\n#top .av-special-heading.av-9oy3-930ed093a6c9b901085fa9835aecad3c{\npadding-bottom:30px;\ncolor:#ffffff;\nfont-size:40px;\n}\nbody .av-special-heading.av-9oy3-930ed093a6c9b901085fa9835aecad3c .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-9oy3-930ed093a6c9b901085fa9835aecad3c .av-special-heading-tag{\nfont-size:40px;\n}\n.av-special-heading.av-9oy3-930ed093a6c9b901085fa9835aecad3c .special-heading-inner-border{\nborder-color:#ffffff;\n}\n.av-special-heading.av-9oy3-930ed093a6c9b901085fa9835aecad3c .av-subheading{\nfont-size:20px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-9oy3-930ed093a6c9b901085fa9835aecad3c .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-9oy3-930ed093a6c9b901085fa9835aecad3c .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-9oy3-930ed093a6c9b901085fa9835aecad3c av-special-heading-h1 custom-color-heading blockquote modern-quote modern-centered  avia-builder-el-16  el_before_av_button  avia-builder-el-first  av-inherit-size'><h1 class='av-special-heading-tag'  itemprop=\"headline\"  >\u00bfInteresado en donar arte? El Museo de Arte de Tucson da la bienvenida a las donaciones relevantes para la misi\u00f3n.<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<div  class='avia-button-wrap av-22wv3-48f6c9a62428f08bccd684535668667f-wrap avia-button-center  avia-builder-el-17  el_after_av_heading  avia-builder-el-last'><a href='https:\/\/www.tucsonmuseumofart.org\/es\/contact\/'  class='avia-button av-22wv3-48f6c9a62428f08bccd684535668667f av-link-btn avia-icon_select-no avia-size-large avia-position-center avia-color-light'   aria-label=\"Cont\u00e1ctenos\"><span class='avia_iconbox_title' >Cont\u00e1ctenos<\/span><\/a><\/div>\n<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":177,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"class_list":["post-35","page","type-page","status-publish","hentry"],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:56:41","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/pages\/35","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/users\/177"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/comments?post=35"}],"version-history":[{"count":10,"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/pages\/35\/revisions"}],"predecessor-version":[{"id":40128,"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/pages\/35\/revisions\/40128"}],"wp:attachment":[{"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/media?parent=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}