{"id":18738,"date":"2020-10-15T11:39:48","date_gmt":"2020-10-15T18:39:48","guid":{"rendered":"https:\/\/www.tucsonmuseumofart.org\/?p=18738"},"modified":"2020-11-04T11:06:21","modified_gmt":"2020-11-04T18:06:21","slug":"las-fotografias-de-mirle-e-freel-junior","status":"publish","type":"post","link":"https:\/\/www.tucsonmuseumofart.org\/es\/las-fotografias-de-mirle-e-freel-junior\/","title":{"rendered":"Las fotograf\u00edas de Mirle E. Freel Junior"},"content":{"rendered":"<div id='av_section_1'  class='avia-section av-29tkc5r-13cfa4b030024f57bd56940d1606158c main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_submenu  avia-builder-el-first  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-18738'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kh0wmhss-078ed1baac2ba85d349321d778ea7338\">\n#top .av-special-heading.av-kh0wmhss-078ed1baac2ba85d349321d778ea7338{\npadding-bottom:0;\n}\nbody .av-special-heading.av-kh0wmhss-078ed1baac2ba85d349321d778ea7338 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-kh0wmhss-078ed1baac2ba85d349321d778ea7338 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-kh0wmhss-078ed1baac2ba85d349321d778ea7338 av-special-heading-h1 blockquote modern-quote modern-centered  avia-builder-el-1  avia-builder-el-no-sibling  av-linked-heading'><h1 class='av-special-heading-tag'  itemprop=\"headline\"  ><a class=\"av-heading-link\" href=\"https:\/\/www.tucsonmuseumofart.org\/es\/tma-stories-blog\/\" >TMA Stories<\/a><\/h1><div class='av-subheading av-subheading_below'><p>A Museum Blog<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div class='clear'><\/div><div id='sub_menu1'  class='av-submenu-container av-kgtsahmy-09c1370a7a0351fa1062772c0c871230 main_color  avia-builder-el-2  el_after_av_section  el_before_av_one_fifth  av-sticky-submenu submenu-not-first container_wrap fullsize' style='z-index:301' ><div class='container av-menu-mobile-disabled av-submenu-pos-center'><ul id='av-custom-submenu-1' class='av-subnav-menu'>\n<li class='menu-item av-4hnupsw-720b0d4451020e0df391364136ac7aca menu-item-top-level menu-item-top-level-1'><a href='https:\/\/www.tucsonmuseumofart.org\/es\/category\/exhibitions\/'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>Exhibitions<\/span><\/a><\/li>\n<li class='menu-item av-3risz1c-065eaf25ff1eb082d870b003af40963a menu-item-top-level menu-item-top-level-2'><a href='https:\/\/www.tucsonmuseumofart.org\/es\/category\/curators-corner\/'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>Curators\u2019 Corner<\/span><\/a><\/li>\n<li class='menu-item av-3aht2lc-0174dad54ab62adc94441e937b1da1fd menu-item-top-level menu-item-top-level-3'><a href='https:\/\/www.tucsonmuseumofart.org\/es\/category\/artists-voices\/'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>Artists\u2019 Voices<\/span><\/a><\/li>\n<li class='menu-item av-2tdapog-c7d91e13c354495dfb6d83a8c9d30747 menu-item-top-level menu-item-top-level-4'><a href='https:\/\/www.tucsonmuseumofart.org\/es\/category\/community-engagement\/'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>Community Engagement<\/span><\/a><\/li>\n<li class='menu-item av-2mppvuo-808ea25f377f1e24f004a2709addbdd6 menu-item-top-level menu-item-top-level-5'><a href='https:\/\/www.tucsonmuseumofart.org\/es\/category\/tma-collection\/'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>Explore Artworks<\/span><\/a><\/li>\n<li class='menu-item av-1yvnytc-be4271c39a0d51984eadc97d4c395b1b menu-item-top-level menu-item-top-level-6'><a href='https:\/\/www.tucsonmuseumofart.org\/es\/category\/digital-content\/'  ><span class='avia-bullet'><\/span><span class='avia-menu-text'>Digital Content<\/span><\/a><\/li>\n<\/ul><\/div><\/div><div class='sticky_placeholder'><\/div><div id='after_submenu_1'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-18738'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mwfbq8-c48772ee88ab81c50a096dafb61dc096\">\n.flex_column.av-mwfbq8-c48772ee88ab81c50a096dafb61dc096{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-mwfbq8-c48772ee88ab81c50a096dafb61dc096 av_one_fifth  avia-builder-el-3  el_after_av_submenu  el_before_av_four_fifth  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-11dslov-41a8b9a7726023a1081214cc1d77c617\">\n.flex_column.av-11dslov-41a8b9a7726023a1081214cc1d77c617{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-11dslov-41a8b9a7726023a1081214cc1d77c617 av_four_fifth  avia-builder-el-4  el_after_av_one_fifth  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-a2cc7c808f5d0b4b8e14679ebbd62f43\">\n#top .av-special-heading.av-av_heading-a2cc7c808f5d0b4b8e14679ebbd62f43{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-av_heading-a2cc7c808f5d0b4b8e14679ebbd62f43 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-a2cc7c808f5d0b4b8e14679ebbd62f43 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-a2cc7c808f5d0b4b8e14679ebbd62f43 av-special-heading-h2 blockquote modern-quote  avia-builder-el-5  el_before_av_post_metadata  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Las fotograf\u00edas de Mirle E. Freel Junior<\/h2><div class='av-subheading av-subheading_below'><p>By Dr. Julie Sasse, Chief Curator<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1aj7r6o-7e69b3ffdaf83da0ce9e4c5ca2a93637\">\n#top .av-post-metadata-container.av-1aj7r6o-7e69b3ffdaf83da0ce9e4c5ca2a93637{\nfont-size:14px;\n}\n#top .av-post-metadata-container.av-1aj7r6o-7e69b3ffdaf83da0ce9e4c5ca2a93637 .av-post-metadata-container-inner{\nfont-size:14px;\n}\n<\/style>\n<div  class='av-post-metadata-container av-1aj7r6o-7e69b3ffdaf83da0ce9e4c5ca2a93637 av-metadata-container-align-left  avia-builder-el-6  el_after_av_heading  el_before_av_hr  av-metadata-container-1'><div class='av-post-metadata-container-inner'><span class=\"av-post-metadata-content av-post-metadata-meta-content\"><span class=\"av-post-metadata-content av-post-metadata-published\"><span class=\"av-post-metadata-published-date\" >octubre 15, 2020<\/span><\/span><span class=\"av-post-metadata-content av-post-metadata-separator\"> | <\/span><span class=\"av-post-metadata-content av-post-metadata-category\"><span class=\"av-post-metadata-category-link\" ><a href=\"https:\/\/www.tucsonmuseumofart.org\/es\/category\/acquisitions\/\" >Acquisitions<\/a><\/span>, <span class=\"av-post-metadata-category-link\" ><a href=\"https:\/\/www.tucsonmuseumofart.org\/es\/category\/curators-corner\/\" >Curators' Corner<\/a><\/span>, <span class=\"av-post-metadata-category-link\" ><a href=\"https:\/\/www.tucsonmuseumofart.org\/es\/category\/exhibitions\/\" >Exhibitions<\/a><\/span>, <span class=\"av-post-metadata-category-link\" ><a href=\"https:\/\/www.tucsonmuseumofart.org\/es\/category\/explore-artworks\/\" >Explore Artworks<\/a><\/span><\/span><\/span><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kgttjgds-3af2862865e26c413068cf56d796f3ad\">\n#top .hr.hr-invisible.av-kgttjgds-3af2862865e26c413068cf56d796f3ad{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-kgttjgds-3af2862865e26c413068cf56d796f3ad hr-invisible  avia-builder-el-7  el_after_av_post_metadata  el_before_av_image '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kgtqxbd1-4ff71d4059a78542917910fa7773c946\">\n.avia-image-container.av-kgtqxbd1-4ff71d4059a78542917910fa7773c946 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-kgtqxbd1-4ff71d4059a78542917910fa7773c946 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-kgtqxbd1-4ff71d4059a78542917910fa7773c946 av-styling- avia-align-center  avia-builder-el-8  el_after_av_hr  el_before_av_textblock '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" class='wp-image-17665 avia-img-lazy-loading-not-17665 avia_image ' src=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2020\/08\/20183734.jpg\" alt='' title='Splash of Glass'  height=\"556\" width=\"850\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2020\/08\/20183734.jpg 850w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2020\/08\/20183734-450x294.jpg 450w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2020\/08\/20183734-300x196.jpg 300w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2020\/08\/20183734-768x502.jpg 768w, https:\/\/www.tucsonmuseumofart.org\/wp-content\/uploads\/2020\/08\/20183734-705x461.jpg 705w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kgv61mm1-d8ddcd03aa02864e331e8be91e03fb1c\">\n#top .av_textblock_section.av-kgv61mm1-d8ddcd03aa02864e331e8be91e03fb1c .avia_textblock{\nfont-size:12px;\n}\n<\/style>\n<section  class='av_textblock_section av-kgv61mm1-d8ddcd03aa02864e331e8be91e03fb1c '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Miele E. Freel, Jr., <em>Untitled<\/em> de la serie \u201cDirect Experience: A Splash of Glass\u201d 1988-1999 (ambas im\u00e1genes), Grabado cibachrome, Regalo del artista.<\/p>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-kf7g22x4-bece1e8f76fbea518d023348f0210f66 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Mirle E. Freel, Jr. toma su inspiraci\u00f3n de las contradicciones de la vida frente a la cara surrealista de la existencia, de la alegr\u00eda frente a la tristeza y de la ansiedad frente a la serenidad.<sup>[1]<\/sup> Se ve a s\u00ed mismo como un observador de la vida y es en este sentido de descubrimiento donde encontramos el fundamento de su fotograf\u00eda y sus pinturas. Del oeste de toda la vida, Freel naci\u00f3 en Casper, Wyoming en 1940 y desarroll\u00f3 un profundo amor por la naturaleza. Freel reflexionaba: \u00abVivir en Wyoming hizo que tuviera conversaciones solitarias con las monta\u00f1as y la vida salvaje, las cuales me eran mucho menos invasivas que la vida salvaje de la ciudad. Las truchas, los alces, los ciervos y los osos tambi\u00e9n eran observadores. Yo caminaba junto a ellos en silencio, con respeto y discreci\u00f3n\u00bb.<sup>[2]<\/sup> Aunque su comportamiento en general era bueno, fue a la escuela militar durante los veranos, ya que sus padres consideraron que ser\u00eda mejor para \u00e9l.<\/p>\n<p>Freel se gradu\u00f3 del instituto de Casper en 1958 y entr\u00f3 enseguida en el colegio universitario de Casper como estudiante de m\u00fasica cl\u00e1sica en la especialidad de canto. Cuando su inter\u00e9s pas\u00f3 a ser la guitarra, no tuvo el coraje de plante\u00e1rselo como especialidad, ya que el colegio no consideraba la guitarra como un instrumento aceptable en una universidad. El punto de inflexi\u00f3n en la vida de Freel le lleg\u00f3 con 18 a\u00f1os cuando Rupert Conrad, profesor de arte en la Universidad de Casper, lo eligi\u00f3 como su protegido y lo llev\u00f3 a un viaje art\u00edstico y cultural por M\u00e9xico. Cuando Freel le dijo a Conrad que le consideraba su mentor, este le respondi\u00f3 sobrecogido: \u00abNo, Mirle, t\u00fa no tienes mentor. T\u00fa eres tu propio mentor\u00bb.<sup>[3]<\/sup> Entonces decidi\u00f3 cambiarse a arte, pues despu\u00e9s de cuatro a\u00f1os de formaci\u00f3n en el extraordinario programa de arte de su instituto, ya conoc\u00eda bien las bases del dibujo y la pintura.<\/p>\n<p>En 1965, tras su paso por el colegio universitario de Casper, Freel fue a la Universidad de Wyoming en Laramie en la que se gradu\u00f3 en educaci\u00f3n con la especializaci\u00f3n de m\u00fasica. En 1966 obtuvo el m\u00e1ster con menci\u00f3n en pintura y dibujo. El programa de arte de la Universidad de Wyoming era estricto, pero Freel agradeci\u00f3 la gran cantidad de buenos profesores que hab\u00eda, incluido el profesor Richard Evans. Para acabar sus estudios de m\u00e1ster, Freel escribi\u00f3 dos trabajos que se convirtieron en inspiraci\u00f3n e influencia de su propia obra. Su primer trabajo, titulado \u00abLa realizaci\u00f3n en el arte\u00bb, era un tratado sobre las obras del fil\u00f3sofo brit\u00e1nico Sir Hebert Reed (1893-1968) y sus ideas acerca del arte como desarrollo de la conciencia.<\/p>\n<p>El segundo trabajo final de m\u00e1ster de Freel fue \u00abBellas Artes para ciegos\u00bb, el cual le consigui\u00f3 un trabajo nada m\u00e1s graduarse en la Escuela de Braille y Problemas Visuales de Iowa en Vinton. All\u00ed dise\u00f1\u00f3 un programa de bellas artes para alumnos desde cuarto de primaria hasta el instituto.<sup>[4]<\/sup> Durante el tiempo que pas\u00f3 all\u00ed, ense\u00f1\u00f3 dibujo, pintura y escultura a ciegos, as\u00ed como fotograf\u00eda a alumnos con visi\u00f3n reducida. Esta experiencia afect\u00f3 fuertemente la forma en la que Freel observaba las cosas a su alrededor y la forma en la que observaba el arte. Desarroll\u00f3 tambi\u00e9n m\u00e9todos y t\u00e9cnicas de dibujo y pintura basadas en aspectos t\u00e1ctiles. Para Freel fue muy gratificante que varios de sus alumnos compitieran en espect\u00e1culos de arte en el instituto de la localidad.<\/p>\n<p>Cuando se encontraba en Vinton conoci\u00f3 a Judy O\u2019Toole, compa\u00f1era suya y profesora de historia, c\u00edvica y pol\u00edtica comparada en la Escuela de Braille y Problemas visuales de Iowa. Se hicieron pareja y m\u00e1s adelante se casaron. Gracias a Freel, O\u2019Toole se interes\u00f3 en el arte, y aunque hubiera tomado ya una clase de arte antes, Freel se convirti\u00f3 en su mentor. Si bien ambos se dedicaban a la creaci\u00f3n de arte, tambi\u00e9n desarrollaron la pasi\u00f3n por la equitaci\u00f3n, y en todos sus movimientos posteriores, se llevaron a sus queridos caballos con ellos. En palabras de Freel: \u00abMontar mis caballos me permit\u00eda llegar a lugares en los que pod\u00eda hacer fotos sin el ruido y la confusi\u00f3n del mundo exterior. Me encanta pasear y montar a caballo a trav\u00e9s del espacio y del tiempo en el momento, en el ahora\u00bb.<\/p>\n<p>En un intento de avanzar en su carrera art\u00edstica, Freel dej\u00f3 su trabajo en la Escuela de Braille y Problemas visuales de Iowa y se mud\u00f3 a la ciudad de Iowa para sacarse un M\u00e1ster de Bellas Artes especializ\u00e1ndose en fotograf\u00eda y en producci\u00f3n de cine en la Universidad de Iowa. En esa \u00e9poca, destac\u00f3 al renombrado fot\u00f3grafo Minor White para un simposio sobre el trabajo de la vida de este y lo entrevist\u00f3 extensamente para su trabajo titulado \u00abMinor White y la luz\u00bb. Despu\u00e9s de su graduaci\u00f3n en 1971, Freel acept\u00f3 un trabajo de profesor en la Universidad de Huron (Dakota del Sur). All\u00ed ense\u00f1\u00f3 arte y m\u00fasica durante su primer a\u00f1o, y luego arte e historia del arte los dos a\u00f1os siguientes. Fue un tiempo apasionante para el artista. En esta \u00e9poca se involucr\u00f3 con el Movimiento Ind\u00edgena Estadounidense (AIM, por sus siglas en ingl\u00e9s) cuando los agentes federales se desplazaron hasta la reserva india de Pine Ridge en Dakota del Sur para apaciguar las acciones de los manifestantes. En una ocasi\u00f3n, John Fire Lamedeer, el m\u00e9dico jefe de los Sioux, fue a su casa para conversar con las secciones locales de nativos americanos a las que un\u00eda Russell Means. Asimismo, tambi\u00e9n fotografi\u00f3 y grab\u00f3 para Eco-etnolog\u00eda a los ind\u00edgenas de las llanuras en colaboraci\u00f3n con Adrian Hannus, lo que deriv\u00f3 finalmente en un programa televisivo fijo de fotograf\u00eda. A petici\u00f3n de Hannus y de un antrop\u00f3logo de Harvard, tambi\u00e9n grab\u00f3 un programa sobre c\u00f3mo las tribus ind\u00edgenas utilizaban la flecha de s\u00edlex para matar b\u00fafalos.<sup>[5]<\/sup><\/p>\n<p>Tres a\u00f1os despu\u00e9s se traslad\u00f3 a la Universidad de Arte y Dise\u00f1o de Columbus (Ohio) en la que lleg\u00f3 a ser responsable del departamento de fotograf\u00eda hasta 1976, cuando se mud\u00f3 de nuevo para ser profesor asociado en el Colegio universitario de Herkimer (SUNY) hasta 1978. En Herkimer, Freel dio clases junto al profesor de artes literarias Stephen Gurney, el cual escribi\u00f3 asombrado sobre la fotograf\u00eda de Freel que:<\/p>\n<blockquote>\n<p>Tal como las palabras de Shelley destacan, el mundo para Freel es como la caverna de Plat\u00f3n: cada imagen es una personificaci\u00f3n borrosa de alg\u00fan esp\u00edritu profundo y arraigado. Freel es un artista puro y rebosa desmesuradamente la cualidad de \u00abcapacidad negativa\u00bb que Keats atribuye al arte supremo.<sup>[6]<\/sup><\/p>\n<\/blockquote>\n<p>El deseo de viajar y la curiosidad de Freel le llevan a mudarse a Tucson en 1978. \u00c9l y O&#8217;Toole encontraron una propiedad de caballos en Ajo Way, en la parte suroeste de la ciudad. En ese tiempo trabaj\u00f3 en el Tucson Museum of Art (TMA) donde creaba ilustraciones y se encargaba de supervisar las relaciones p\u00fablicas de la instituci\u00f3n. De igual modo se convirti\u00f3 en el primer instructor de fotograf\u00eda a tiempo completo de la escuela de arte del TMA. Ah\u00ed trabajaba con John McNulty, que ense\u00f1aba cer\u00e1mica, y con Renee Verdugo, registradora, fot\u00f3grafa y pintora.<sup>[7]<\/sup> Incluso entonces el trabajo de Freel con las personas con ceguera ya destacaba. Comparti\u00f3 su investigaci\u00f3n con John Kennedy, doctorando en psicolog\u00eda y profesor en la Universidad de Scarborough (Toronto, Canad\u00e1). En 1979 conoci\u00f3 al c\u00e9lebre fil\u00f3sofo Rudolf Arnheim, el cual hab\u00eda visto su art\u00edculo sobre arte para las personas con ceguera. Arnheim habl\u00f3 en el Tucson Museum of Art como parte de un programa del Consorcio de Artistas Visitantes de la ciudad. Ambos compartieron sus investigaciones, lo que potenci\u00f3 el inter\u00e9s de Freel en el tema. Ese mismo a\u00f1o imparti\u00f3 un taller en la Universidad de Arizona sobre arte para las personas con discapacidad visual. Tambi\u00e9n solicit\u00f3 y recibi\u00f3 una beca para desarrollar un programa similar en la universidad.<\/p>\n<p>Freel continu\u00f3 con su estudio y con la ense\u00f1anza de arte a personas con discapacidad visual a la vez que trabajaba en el TMA. Se uni\u00f3 al espacio creativo de Dinnerware Artspace en Tucson y entr\u00f3 a formar parte de la comunidad de artistas del sur de Arizona.<sup>[8]<\/sup> En esta \u00e9poca se centr\u00f3 en la pintura y la fotograf\u00eda de motivos realistas tra\u00eddos desde la experiencia vital, incluidos retratos, paisajes urbanos arquitect\u00f3nicos y figuras de Tucson. Sigui\u00f3 explorando tambi\u00e9n la idea de los paisajes subconscientes.<\/p>\n<p>En 1979 present\u00f3 una exposici\u00f3n individual en el TMA, se llam\u00f3 \u00abEl sentido de la forma\u00bb, que sigui\u00f3 exponiendo por todo el pa\u00eds. Freel se sent\u00eda como en casa en Tucson, para \u00e9l era un peque\u00f1o pueblo del oeste protot\u00edpico y despoblado, perfecto para cuidar sus caballos y hacer sus fotograf\u00edas. Adem\u00e1s, se sent\u00eda parte de una comunidad art\u00edstica en auge. Pero a Freel le quedaban aventuras por vivir, y dos a\u00f1os despu\u00e9s, acept\u00f3 un trabajo en la Universidad de Southwestern en Creston (Iowa) y se permaneci\u00f3 all\u00ed hasta 1987. En esa \u00e9poca, \u00e9l y su esposa Judy montaban a caballo por el campo y jugaban al polo y al polocrosse tradicional, tal y como hab\u00edan hecho en cada sitio que hab\u00edan vivido. Mientras viv\u00edan all\u00ed a\u00f1adieron tambi\u00e9n cazar zorros a su lista de actividades de ocio.<\/p>\n<p>Siempre dispuesto a atreverse con nuevos movimientos en su carrera, en 1989 Freel acept\u00f3 un puesto en la Universidad de Great Falls (Montana), en la que desarroll\u00f3 el programa del grado de Bellas Artes de 4 a\u00f1os y se qued\u00f3 durante los nueve a\u00f1os siguientes.<sup>[9]<\/sup> Mientras estaba en Montana, cre\u00f3 bodegones occidentales, pinturas acr\u00edlicas no objetivas sobre lienzo y pinturas digitales. Tambi\u00e9n hizo retratos y dibujos de grafito. Asimismo, explor\u00f3 el subconsciente a trav\u00e9s de construcciones fotogr\u00e1ficas con luces y de la escultura cer\u00e1mica. Adem\u00e1s, empez\u00f3 a ilustrar dos libros infantiles que hab\u00eda escrito su esposa Judy. Un proyecto que continuaron despu\u00e9s de irse de Montana.<\/p>\n<p>Tras pasar un tiempo en Iowa cuidando de los padres de su esposa Judy, Freel dej\u00f3 la ense\u00f1anza en el a\u00f1o 2000 y se volvieron a Tucson. El tiempo c\u00e1lido y las monta\u00f1as de all\u00ed les llamaban. Sin embargo, aunque ten\u00eda buenos recuerdos de Tucson y de su experiencia en el TMA, regres\u00f3 a una ciudad diferente, muy diferente de la que hab\u00eda dejado al marcharse. Le segu\u00eda encantando Tucson, pero ya no era una peque\u00f1a y unida comunidad art\u00edstica. La ciudad hab\u00eda crecido y el panorama cultural no se hab\u00eda quedado atr\u00e1s. Se compraron una propiedad residencial en la zona noroeste de la ciudad, justo al lado de Twin Peaks Road, y montaron estudios con su caballo en un establo cercano. Desde entonces Freel ha pintado y fotografiado con la misma pasi\u00f3n. Seg\u00fan Freel: \u00abLa pintura me ha influido mucho porque fue mi primera carrera. El dibujo y la pintura influyen la forma en la que pienso sobre la fotograf\u00eda\u00bb.<sup>[10]<\/sup><\/p>\n<p>Para crear sus pinturas y sus fotograf\u00edas, Freel descubre estampas de bodegones en la vida real o coloca objetos para dirigir la composici\u00f3n. Del mismo modo que las ciudades y los paisajes en los que ha vivido a lo largo de los a\u00f1os le han inspirado, tambi\u00e9n lo hicieron sus muchos viajes, a menudo a caballo, a lugares entre los que se encuentra Irlanda, Reino Unido, Francia, M\u00e9xico, Canad\u00e1, Jamaica y todos los Estados Unidos. Freel ve su obra como una exploraci\u00f3n de tres mentes: las derivaciones del subconsciente y las im\u00e1genes surrealistas; la experiencia directa; y la manipulaci\u00f3n de la composici\u00f3n, especialmente las pinturas no objetivas y no representativas. Igualmente, la m\u00fasica, su primera pasi\u00f3n, le sigue influyendo y compara sus pinturas no objetivas con una partitura musical.<\/p>\n<p>La selecci\u00f3n de las fotograf\u00edas de Freel en esta exposici\u00f3n viene de cinco series. Una de las series es \u00abSobre la luz\u00bb, en la cual la luz natural entra por una ventana en una escena interior. En estas obras, la luz y las sobras tienen un papel muy importante en la ambientaci\u00f3n y las cualidades m\u00e1gicas de la composici\u00f3n. Otra de las series se centra en bodegones interiores que fotografi\u00f3 en Horetown (Irlanda) en una finca ecuestre. Freel prefiere que sea la intuici\u00f3n la que gu\u00ede la est\u00e9tica de sus elecciones en la fotograf\u00eda. Algunas obras de esta serie eran im\u00e1genes que se le ocurrieron, sin estar definidas por una programaci\u00f3n o una declaraci\u00f3n. De esta forma, el espectador experimenta el encuentro casual del fot\u00f3grafo con una sensaci\u00f3n de descubrimiento compartido. Otra serie fue tomada en Tucson. Esta se centra en la luz y en c\u00f3mo interact\u00faa con una mujer que nada en una piscina. Ella se desliza a trav\u00e9s del agua turquesa que distorsiona su forma y la transforma en abstracci\u00f3n. \u00abLa m\u00e1scara\u00bb es el resultado de colocar utiler\u00eda en un escenario formal de bodeg\u00f3n. La revista de arte <em>Art News<\/em>en \u00abArts of the American West\u00bb public\u00f3 una rese\u00f1a sobre este conjunto de obras. La serie final se centra en la relaci\u00f3n entre la cualidad reflectante del vidrio y la naturaleza temporal de una mariposa. En estas obras, las sombras juegan un papel esencial en la complejidad visual de la composici\u00f3n.<\/p>\n<p>Finalmente, Freel responde de forma art\u00edstica a su propia musa, dejando que la serendipia gu\u00ede sus ideas. Al encontrar la belleza en el mundo que le rodea, refleja una mente interior en paz y una mente consciente inquisitiva y po\u00e9tica. La simplicidad de su visi\u00f3n se observa en su forma de ver de la vida. \u00abNo tengo segundas intenciones, para m\u00ed la vida es un camino arduo que recorrer. Mi arte, mi pareja Judy, mis caballos y mis perros, la pesca con mosca, y las monta\u00f1as y sus habitantes han sido mi constante fuerza vital\u00bb, dijo Freel.<sup>[11]<\/sup><\/p>\n<p><em>Las fotograf\u00edas de Mirle E. Freel, Jr. estar\u00e1n a la vista hasta el 29 de agosto de 2021 en la Galer\u00eda Kenneth J. y Judith H. Riskind\/Patricia Carr Morgan y Peter F. Salomon en el Tucson Museum of Art.<\/em><\/p>\n<\/div><\/section><br \/>\n<div  class='hr av-x0ur64-d4c8be63a66101d8f678b2e8ae8fd0b8 hr-default  avia-builder-el-11  el_after_av_textblock  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-kf7g22x4-bece1e8f76fbea518d023348f0210f66 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p>[1] Mirle E. Freel Jr., correo electr\u00f3nico al autor, 23 de junio de 2020.<\/p>\n<p>[2] Mirle E. Freel Jr., correo electr\u00f3nico al autor, 23 de junio de 2020.<\/p>\n<p>[3] Rupert Conrad cita un correo electr\u00f3nico de Mirle E. Freel, Jr. al autor, 23 de junio de 2020. Entre otros amigos que inspiraron a Freel contamos a Roger Camp, profesor de fotograf\u00eda con el que ense\u00f1aba en la Universidad de Arte y Dise\u00f1o de Columbus (Ohio)\u00a0y Rene Verdugo, pintora y fot\u00f3grafa de Tucson con la que ense\u00f1\u00f3 en la escuela del Museo de Arte de Tucson en la d\u00e9cada de los 70.<\/p>\n<p>[4] El programa de Bellas Artes de Freel en la Escuela de Braille y Problemas visuales de Iowa se cita como uno de los m\u00e1s innovadores de Iowa y a \u00e9l se le cita como uno de los instructores de arte m\u00e1s innovadores en la publicaci\u00f3n de arte <em>The Iowa Alliance for Arts Education Newsletter<\/em>. Su investigaci\u00f3n y su ense\u00f1anza sobre arte para las personas con ceguera se public\u00f3 en mayo de 1969 en la revista educativa <em>Education of the Visually Handicapped<\/em>.<\/p>\n<p>[5] Freel recuerda perfectamente la grabaci\u00f3n de este programa porque el antrop\u00f3logo sali\u00f3 corriendo para ver el resultado de la matanza, sin darse cuenta de que los b\u00fafalos rodean a sus presas. As\u00ed se puso en peligro inminente hasta que un ganadero due\u00f1o de la manada rompi\u00f3 el c\u00edrculo con su cami\u00f3n. Mirle E. Freel Jr., correo electr\u00f3nico al autor, 23 de junio de 2020.<\/p>\n<p>[6] Stephen Gurney, declaraci\u00f3n no publicada usada en materiales promocionales del artista, 1976.<\/p>\n<p>[7] John McNulty finalmente lleg\u00f3 a ser el encargado de la tienda del TMA y trabaj\u00f3 all\u00ed m\u00e1s de 30 a\u00f1os.<\/p>\n<p>[8] La ceramista Barbara Grygutis fue una de las m\u00e1s notables artistas que trabaj\u00f3 en el espacio creativo de Dinnerware Artspace a finales de la d\u00e9cada de los 70. Cuando el Templo de la M\u00fasica y las Artes expuso una gran antolog\u00eda de artistas del espacio creativo de Dinnerware Artspace, incluyeron a Freel en la exposici\u00f3n.<\/p>\n<p>[9] La Universidad de Great Falls (Montana) pas\u00f3 a ser la Universidad de Providencia en 2017.<\/p>\n<p>[10] Mirle E. Freel Jr., correo electr\u00f3nico al autor, 23 de junio de 2020.<\/p>\n<p>[11] Mirle E. Freel Jr., correo electr\u00f3nico al autor, 23 de junio de 2020.<\/p>\n<\/div><\/section><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":177,"featured_media":17665,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[125,127,130,137],"tags":[],"class_list":["post-18738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acquisitions","category-curators-corner","category-exhibitions","category-explore-artworks"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 13:40:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/posts\/18738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/users\/177"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/comments?post=18738"}],"version-history":[{"count":5,"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/posts\/18738\/revisions"}],"predecessor-version":[{"id":19053,"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/posts\/18738\/revisions\/19053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/media\/17665"}],"wp:attachment":[{"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/media?parent=18738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/categories?post=18738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tucsonmuseumofart.org\/es\/wp-json\/wp\/v2\/tags?post=18738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}